{"id":3841,"date":"2021-03-22T17:06:38","date_gmt":"2021-03-22T08:06:38","guid":{"rendered":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1.jpg"},"modified":"2021-03-22T17:06:38","modified_gmt":"2021-03-22T08:06:38","slug":"2105_sushi1","status":"inherit","type":"attachment","link":"https:\/\/www.betterhome.jp\/school\/oneday\/2105_sushi1","title":{"rendered":"2105_sushi1"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3841","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"215\" height=\"215\" src=\"https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":215,"height":215,"file":"2021\/03\/2105_sushi1.jpg","sizes":{"thumbnail":{"file":"2105_sushi1-215x215.jpg","width":215,"height":215,"mime_type":"image\/jpeg","source_url":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1-215x215.jpg"},"post-thumbnail":{"file":"2105_sushi1-215x198.jpg","width":215,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1-215x198.jpg"},"full":{"file":"2105_sushi1.jpg","width":215,"height":215,"mime_type":"image\/jpeg","source_url":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-content\/uploads\/2021\/03\/2105_sushi1.jpg","filename":"2105_sushi1.jpg","filesize":59535,"_links":{"self":[{"href":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-json\/wp\/v2\/media\/3841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.betterhome.jp\/school\/oneday\/wp-json\/wp\/v2\/comments?post=3841"}]}}